{"id":2685,"date":"2017-06-26T14:17:48","date_gmt":"2017-06-26T14:17:48","guid":{"rendered":"http:\/\/cerareus.com\/info\/?page_id=2685\/"},"modified":"2017-07-17T10:17:35","modified_gmt":"2017-07-17T10:17:35","slug":"modelling-waxes-category","status":"publish","type":"page","link":"https:\/\/cerareus.com\/info\/en\/modelling-waxes-category\/","title":{"rendered":"MODELLING WAXES"},"content":{"rendered":"\t<div id=\"gap-1661590033\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1661590033 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<style scoped>.box-overlay.dark .box-text,.box-shade.dark .box-text {padding-left: 10px;padding-right: 10px;}<\/style>\r\n\r\n<div class=\"row row-collapse\"  id=\"row-1252516824\">\r\n\r\n\n\t<div id=\"col-1123193223\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-shadow-1-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"http:\/\/cerareus.com\/info\/en\/modelling-waxes\/\" >\t\t\t<div class=\"image-overlay-remove-50 image-zoom image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"562\" height=\"364\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal.png 562w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-510x330.png 510w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h2><a href=\"http:\/\/cerareus.com\/info\/en\/modelling-waxes\/\">MODELLING WAXES<\/a><\/h2>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-935682832\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-shadow-1-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"http:\/\/cerareus.com\/info\/en\/special-modelling-waxes\/\" >\t\t\t<div class=\"image-overlay-remove-50 image-zoom image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1016\" height=\"793\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red.jpg 1016w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-510x398.jpg 510w\" sizes=\"auto, (max-width: 1016px) 100vw, 1016px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h2><a href=\"http:\/\/cerareus.com\/info\/en\/special-modelling-waxes\/\">SPECIAL MODELLING WAXES<\/a><\/h2>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1758561216\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-shadow-1-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"http:\/\/cerareus.com\/info\/en\/universal-modelling-waxes\/\" >\t\t\t<div class=\"image-overlay-remove-50 image-zoom image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"556\" height=\"406\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-universal.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-universal.jpg 556w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-universal-510x372.jpg 510w\" sizes=\"auto, (max-width: 556px) 100vw, 556px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h2><a href=\"http:\/\/cerareus.com\/info\/en\/universal-modelling-waxes\/\">UNIVERSAL MODELLING WAXES<\/a><\/h2>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n\n<style>\n#row-1252516824 > .col > .col-inner {\n  padding: 0px 3px 0px 3px;\n}\n@media (min-width:550px) {\n  #row-1252516824 > .col > .col-inner {\n    padding: 0px 3px 0px 3px;\n  }\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-899322216\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-899322216 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<section class=\"section dark has-mask mask-arrow hide-for-small\" id=\"section_365590719\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-divided\"  id=\"row-502745365\">\n\n\t<div id=\"col-365561212\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/cerareus.com\/info\/en\/modelling-waxes\/\">NORMAL MODELLING<\/a><\/h3>\n<p>Multi-purpose standard pink modelling wax, adequate for works with removable prosthesis and jewellery.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1304109722\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/cerareus.com\/info\/en\/special-modelling-waxes\/\">SPECIAL MODELLING<\/a><\/h3>\n<p>The special waxes have been designed to satisfy all the dental prosthesis requirements.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1752736686\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/cerareus.com\/info\/en\/universal-modelling-waxes\/\">UNIVERSAL MODELLING<\/a><\/h3>\n<p>Multi-purpose modelling wax, ideal for removable prosthesis.\u00a0This type of wax in light pink colour is one of the most common for the European professionals.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_365590719 {\n  padding-top: 35px;\n  padding-bottom: 35px;\n  background-color: rgb(0,0,0);\n}\n#section_365590719 .section-bg-overlay {\n  background-color: #A58326;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"accordion\">\n\t<div id=\"accordion-572626857\" class=\"accordion-item\">\n\t\t<a id=\"accordion-572626857-label\" class=\"accordion-title plain\" href=\"#accordion-item-normal_modelling_waxes\" aria-expanded=\"false\" aria-controls=\"accordion-572626857-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>NORMAL MODELLING WAXES<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-572626857-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-572626857-label\" >\n\t\t\t\n<ul class=\"product_list_widget\">\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/hot-climates-modelling-wax-2500g-economic-packaging\/\" title=\"HOT CLIMATES MODELLING WAX 2500G ECONOMIC PACKAGING\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"HOT CLIMATES MODELLING WAX 2500G ECONOMIC PACKAGING\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">HOT CLIMATES MODELLING WAX 2500G ECONOMIC PACKAGING<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/hot-climates-modelling-wax-450g\/\" title=\"HOT CLIMATES MODELLING WAX 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"HOT CLIMATES MODELLING WAX 450G\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">HOT CLIMATES MODELLING WAX 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/normal-modelling-wax-jewellery-450g-2mm\/\" title=\"NORMAL MODELLING WAX JEWELLERY 450G 2MM\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"NORMAL MODELLING WAX JEWELLERY 450G 2MM\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">NORMAL MODELLING WAX JEWELLERY 450G 2MM<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/normal-modelling-wax-jewellery-450g-1mm\/\" title=\"NORMAL MODELLING WAX JEWELLERY 450G 1MM\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"NORMAL MODELLING WAX JEWELLERY 450G 1MM\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">NORMAL MODELLING WAX JEWELLERY 450G 1MM<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/normal-pink-modelling-wax-jewellery-450g-rsr-calibers-6-26-1-58-1-mm\/\" title=\"NORMAL PINK MODELLING WAX JEWELLERY 450G RSR CALIBERS 6-2\/6-1.5\/8-1 MM\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"NORMAL PINK MODELLING WAX JEWELLERY 450G RSR CALIBERS 6-2\/6-1.5\/8-1 MM\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">NORMAL PINK MODELLING WAX JEWELLERY 450G RSR CALIBERS 6-2\/6-1.5\/8-1 MM<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/normal-pink-modelling-wax-2500g-economic-packaging\/\" title=\"NORMAL PINK MODELLING WAX 2500G ECONOMIC PACKAGING\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"NORMAL PINK MODELLING WAX 2500G ECONOMIC PACKAGING\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">NORMAL PINK MODELLING WAX 2500G ECONOMIC PACKAGING<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/normal-pink-modelling-wax-450g\/\" title=\"NORMAL PINK MODELLING WAX 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"NORMAL PINK MODELLING WAX 450G\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-100x100.png 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-de-modelar-normal-280x280.png 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">NORMAL PINK MODELLING WAX 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n        \n      <\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1974809922\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1974809922-label\" class=\"accordion-title plain\" href=\"#accordion-item-special_modelling_waxes\" aria-expanded=\"false\" aria-controls=\"accordion-1974809922-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>SPECIAL MODELLING WAXES<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1974809922-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1974809922-label\" >\n\t\t\t\n<ul class=\"product_list_widget\">\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/special-modelling-wax-white-450g\/\" title=\"SPECIAL MODELLING WAX WHITE 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-white-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"SPECIAL MODELLING WAX WHITE 450G\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-white-100x100.jpg 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-white-280x280.jpg 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">SPECIAL MODELLING WAX WHITE 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/special-modelling-wax-dark-red-450g\/\" title=\"SPECIAL MODELLING WAX DARK RED 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"SPECIAL MODELLING WAX DARK RED 450G\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-100x100.jpg 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-280x280.jpg 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">SPECIAL MODELLING WAX DARK RED 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/special-modelling-wax-red-450g\/\" title=\"SPECIAL MODELLING WAX RED 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"SPECIAL MODELLING WAX RED 450G\" srcset=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-100x100.jpg 100w, https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/06\/Cera-modelar-special-red-280x280.jpg 280w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/>\t\t<span class=\"product-title\">SPECIAL MODELLING WAX RED 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/special-modelling-wax-pink-450g\/\" title=\"SPECIAL MODELLING WAX PINK 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/05\/SPECIAL-PINK-3-ret-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"SPECIAL MODELLING WAX PINK 450G\" \/>\t\t<span class=\"product-title\">SPECIAL MODELLING WAX PINK 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n        \n      <\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-257299219\" class=\"accordion-item\">\n\t\t<a id=\"accordion-257299219-label\" class=\"accordion-title plain\" href=\"#accordion-item-universal_modelling_waxes\" aria-expanded=\"false\" aria-controls=\"accordion-257299219-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>UNIVERSAL MODELLING WAXES<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-257299219-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-257299219-label\" >\n\t\t\t\n<ul class=\"product_list_widget\">\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/universal-modelling-wax-summer-pale-pink-450g\/\" title=\"UNIVERSAL MODELLING WAX SUMMER PALE PINK 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/04\/ceramoduniv5-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"UNIVERSAL MODELLING WAX SUMMER PALE PINK 450G\" \/>\t\t<span class=\"product-title\">UNIVERSAL MODELLING WAX SUMMER PALE PINK 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n                  <li>\n\t<a href=\"https:\/\/cerareus.com\/info\/en\/producto\/universal-modelling-wax-winter-pale-pink-450g\/\" title=\"UNIVERSAL MODELLING WAX WINTER PALE PINK 450G\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/cerareus.com\/info\/wp-content\/uploads\/2017\/04\/ceramoduniv5-100x100.jpg\" class=\"attachment-woocommerce_gallery_thumbnail size-woocommerce_gallery_thumbnail\" alt=\"UNIVERSAL MODELLING WAX WINTER PALE PINK 450G\" \/>\t\t<span class=\"product-title\">UNIVERSAL MODELLING WAX WINTER PALE PINK 450G<\/span>\n\t<\/a>\n\t\t<\/li>\n        \n      <\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-2685","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/pages\/2685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/comments?post=2685"}],"version-history":[{"count":7,"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/pages\/2685\/revisions"}],"predecessor-version":[{"id":3843,"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/pages\/2685\/revisions\/3843"}],"wp:attachment":[{"href":"https:\/\/cerareus.com\/info\/en\/wp-json\/wp\/v2\/media?parent=2685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}